{"id":1034,"date":"2023-07-05T19:44:43","date_gmt":"2023-07-05T19:44:43","guid":{"rendered":"https:\/\/divingfuns.com\/es\/?post_type=product&#038;p=1034"},"modified":"2025-05-30T00:08:22","modified_gmt":"2025-05-30T00:08:22","slug":"curso-10-padi-master-scuba-diver","status":"publish","type":"product","link":"https:\/\/divingfuns.com\/es\/product\/curso-10-padi-master-scuba-diver\/","title":{"rendered":"CURSO 10 Master Scuba Diver"},"content":{"rendered":"<p><strong>Maestro Buceador<\/strong><\/p>\n<p>\u00danete a la crema de la crema del buceo recreativo. El nivel de Master Scuba Diver te situa en el grupo elite de buceadores respetados que han logrado este nivel a trav\u00e9s de experiencia como entrenamiento. Cuando muestras tu tarjeta de Master Scuba Diver, la gente sabe que haz pasado tiempo bajo el agua en una variedad de entornos y has tenido tus aventuras de buceo.<\/p>\n<p>\ud83d\udd39 Edad m\u00ednima 12 a\u00f1os<br \/>\n\ud83d\udd39 Nivel junior Open Water Diver<br \/>\n\ud83d\udd39Nivel Junior Advanced Open Water Diver<br \/>\n\ud83d\udd39Nivel Junior Rescue Diver<br \/>\n\ud83d\udd39Necesitas 5 certificaciones de especialidad<br \/>\n\ud83d\udd39 M\u00ednimo 50 inmersiones registradas<\/p>\n<p><strong>INCLUYE<\/strong><br \/>\n\ud83d\udd39 Teor\u00eda-Practica<br \/>\n\ud83d\udd39 Carnet De Certificaci\u00f3n<br \/>\n\ud83d\udd39 Equipo Para Entrenamiento<br \/>\n\ud83d\udd39 Inmersiones<br \/>\n\ud83d\udd39 Snack-Agua<br \/>\n\ud83d\udd39 Traslado hotel-punto buceo-hotel<br \/>\n\ud83d\udd39 Seguro Colasistencia<\/p>\n<p><strong>Nota:<\/strong> Cobraremos una tasa de cancelaci\u00f3n del 50% del abono si cancelas la reserva 72 horas antes de empezar la actividad.<br \/>\nCobramos una tasa de cancelaci\u00f3n del 70% del abono si cancelas la reserva 12 horas antes de empezar la actividad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maestro Buceador \u00danete a la crema de la crema del buceo recreativo. El nivel de Master Scuba Diver te situa en el grupo elite de buceadores respetados que han logrado [&hellip;]<\/p>\n","protected":false},"featured_media":1572,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[46],"product_tag":[],"class_list":{"0":"post-1034","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cursos","8":"first","9":"onbackorder","10":"sale","11":"downloadable","12":"virtual","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product\/1034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/comments?post=1034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/media\/1572"}],"wp:attachment":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/media?parent=1034"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product_brand?post=1034"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product_cat?post=1034"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product_tag?post=1034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}