{"id":1047,"date":"2023-07-05T20:20:06","date_gmt":"2023-07-05T20:20:06","guid":{"rendered":"https:\/\/divingfuns.com\/es\/?post_type=product&#038;p=1047"},"modified":"2024-07-29T23:13:35","modified_gmt":"2024-07-29T23:13:35","slug":"curso-16-freediver","status":"publish","type":"product","link":"https:\/\/divingfuns.com\/es\/product\/curso-16-freediver\/","title":{"rendered":"CURSO 16 Freedier"},"content":{"rendered":"<p><strong>Apnea<\/strong><\/p>\n<p>Freediver. Trata el poder interior, disciplina y control, si siempre has deseado entrar en el mundo subacuatico, permanecer tanto tiempo como te lo permita tu respiraci\u00f3n entonces el Freediver PADI es para ti. Hacer el curso es tu primer paso para descubrir por que el Freediving se est\u00e1 convirtiendo en una manera popular de explorar bajo las olas.<\/p>\n<p>\ud83d\udd39 Edad m\u00ednima 15 a\u00f1os<br \/>\n\ud83d\udd39 T\u00e9cnicas Nataci\u00f3n<br \/>\n\ud83d\udd39 Buen estado F\u00edsico<\/p>\n<p>Nota: Cobraremos una tasa de cancelaci\u00f3n del 50% del abono si cancelas la reserva 72 horas antes de empezar la actividad.<br \/>\nCobramos una tasa de cancelaci\u00f3n del 70% del abono si cancelas la reserva 12 horas antes de empezar la actividad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apnea Freediver. Trata el poder interior, disciplina y control, si siempre has deseado entrar en el mundo subacuatico, permanecer tanto tiempo como te lo permita tu respiraci\u00f3n entonces el Freediver [&hellip;]<\/p>\n","protected":false},"featured_media":1453,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[46],"product_tag":[],"class_list":{"0":"post-1047","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cursos","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/comments?post=1047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/media\/1453"}],"wp:attachment":[{"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/media?parent=1047"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product_brand?post=1047"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product_cat?post=1047"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divingfuns.com\/es\/wp-json\/wp\/v2\/product_tag?post=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}